{"id":1004,"count":1,"description":"","link":"https:\/\/studiotwoonetwo.com\/blog\/tag\/clemson-seniors\/","name":"Clemson Seniors","slug":"clemson-seniors","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Clemson Seniors Archives - Florence SC Wedding, Engagement and Portrait Photographer<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/studiotwoonetwo.com\/blog\/tag\/clemson-seniors\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Clemson Seniors Archives - Florence SC Wedding, Engagement and Portrait Photographer\" \/>\n<meta property=\"og:url\" content=\"https:\/\/studiotwoonetwo.com\/blog\/tag\/clemson-seniors\/\" \/>\n<meta property=\"og:site_name\" content=\"Florence SC Wedding, Engagement and Portrait Photographer\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/studiotwoonetwo.com\\\/blog\\\/tag\\\/clemson-seniors\\\/\",\"url\":\"https:\\\/\\\/studiotwoonetwo.com\\\/blog\\\/tag\\\/clemson-seniors\\\/\",\"name\":\"Clemson Seniors Archives - Florence SC Wedding, Engagement and Portrait Photographer\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.studiotwoonetwo.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/studiotwoonetwo.com\\\/blog\\\/tag\\\/clemson-seniors\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/studiotwoonetwo.com\\\/blog\\\/tag\\\/clemson-seniors\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.studiotwoonetwo.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Clemson Seniors\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.studiotwoonetwo.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.studiotwoonetwo.com\\\/blog\\\/\",\"name\":\"Florence SC Wedding, Engagement and Portrait Photographer\",\"description\":\"Wedding, Engagement and Portrait Photography by Patty Pound, Certified Professional Photographer in the Florence, SC area.  Available for travel.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.studiotwoonetwo.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.studiotwoonetwo.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.studiotwoonetwo.com\\\/blog\\\/#organization\",\"name\":\"Florence SC Wedding, Engagement and Portrait Photographer\",\"url\":\"https:\\\/\\\/www.studiotwoonetwo.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.studiotwoonetwo.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/studiotwoonetwo.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/cropped-studio-two-One-two-copy.jpg\",\"contentUrl\":\"https:\\\/\\\/studiotwoonetwo.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/cropped-studio-two-One-two-copy.jpg\",\"width\":2310,\"height\":475,\"caption\":\"Florence SC Wedding, Engagement and Portrait Photographer\"},\"image\":{\"@id\":\"https:\\\/\\\/www.studiotwoonetwo.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Clemson Seniors Archives - Florence SC Wedding, Engagement and Portrait Photographer","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/studiotwoonetwo.com\/blog\/tag\/clemson-seniors\/","og_locale":"en_US","og_type":"article","og_title":"Clemson Seniors Archives - Florence SC Wedding, Engagement and Portrait Photographer","og_url":"https:\/\/studiotwoonetwo.com\/blog\/tag\/clemson-seniors\/","og_site_name":"Florence SC Wedding, Engagement and Portrait Photographer","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/studiotwoonetwo.com\/blog\/tag\/clemson-seniors\/","url":"https:\/\/studiotwoonetwo.com\/blog\/tag\/clemson-seniors\/","name":"Clemson Seniors Archives - Florence SC Wedding, Engagement and Portrait Photographer","isPartOf":{"@id":"https:\/\/www.studiotwoonetwo.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/studiotwoonetwo.com\/blog\/tag\/clemson-seniors\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/studiotwoonetwo.com\/blog\/tag\/clemson-seniors\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.studiotwoonetwo.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Clemson Seniors"}]},{"@type":"WebSite","@id":"https:\/\/www.studiotwoonetwo.com\/blog\/#website","url":"https:\/\/www.studiotwoonetwo.com\/blog\/","name":"Florence SC Wedding, Engagement and Portrait Photographer","description":"Wedding, Engagement and Portrait Photography by Patty Pound, Certified Professional Photographer in the Florence, SC area.  Available for travel.","publisher":{"@id":"https:\/\/www.studiotwoonetwo.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.studiotwoonetwo.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.studiotwoonetwo.com\/blog\/#organization","name":"Florence SC Wedding, Engagement and Portrait Photographer","url":"https:\/\/www.studiotwoonetwo.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.studiotwoonetwo.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/studiotwoonetwo.com\/blog\/wp-content\/uploads\/2018\/03\/cropped-studio-two-One-two-copy.jpg","contentUrl":"https:\/\/studiotwoonetwo.com\/blog\/wp-content\/uploads\/2018\/03\/cropped-studio-two-One-two-copy.jpg","width":2310,"height":475,"caption":"Florence SC Wedding, Engagement and Portrait Photographer"},"image":{"@id":"https:\/\/www.studiotwoonetwo.com\/blog\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/studiotwoonetwo.com\/blog\/wp-json\/wp\/v2\/tags\/1004","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/studiotwoonetwo.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/studiotwoonetwo.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/studiotwoonetwo.com\/blog\/wp-json\/wp\/v2\/posts?tags=1004"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}